{"id":37072,"date":"2026-05-13T11:05:06","date_gmt":"2026-05-13T09:05:06","guid":{"rendered":"https:\/\/espacehealth.ch\/?post_type=job&#038;p=37072"},"modified":"2026-05-13T11:08:59","modified_gmt":"2026-05-13T09:08:59","slug":"assistenzarzt-m-w-d-fachrichtung-allgemeine-innere-medizin-4","status":"publish","type":"job","link":"https:\/\/espacehealth.ch\/fr\/job\/assistenzarzt-m-w-d-fachrichtung-allgemeine-innere-medizin-4\/","title":{"rendered":"Assistenzarzt (m\/w\/d) Fachrichtung Allgemeine Innere Medizin"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ab Februar 2027 in unserem Standort in\u00a0<strong>Heimberg<\/strong>\u00a0\u2013 suchen wir engagierte Assistenz\u00e4rztinnen und Assistenz\u00e4rzte, die unsere Vision teilen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei&nbsp;<strong>Espace Health<\/strong>&nbsp;setzen wir auf echte Zusammenarbeit: integriert, interdisziplin\u00e4r und zukunftsorientiert. Du arbeitest Hand in Hand mit unseren&nbsp;<strong>Pharmacies<\/strong>,&nbsp;<strong>APNs<\/strong>, unserer&nbsp;<strong>Digitalagentur<\/strong>&nbsp;mit eigenem Versicherungsmodell und der firmeneigenen&nbsp;<strong>Spitex<\/strong>&nbsp;\u2013 und profitierst von der engen Kooperation mit&nbsp;<strong>Spit\u00e4lern<\/strong>&nbsp;und&nbsp;<strong>Labors<\/strong>.<\/p>","protected":false},"featured_media":35727,"template":"","meta":{"_acf_changed":true,"_gspb_post_css":""},"class_list":["post-37072","job","type-job","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/espacehealth.ch\/fr\/wp-json\/wp\/v2\/job\/37072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacehealth.ch\/fr\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/espacehealth.ch\/fr\/wp-json\/wp\/v2\/types\/job"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacehealth.ch\/fr\/wp-json\/wp\/v2\/media\/35727"}],"wp:attachment":[{"href":"https:\/\/espacehealth.ch\/fr\/wp-json\/wp\/v2\/media?parent=37072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}